{"id":125,"count":7,"description":"","link":"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/","name":"Public work","slug":"public-work","taxonomy":"categoria-proyecto","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Public work archivos - Huurre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Public work archivos - Huurre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/\" \/>\n<meta property=\"og:site_name\" content=\"Huurre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/project-category\\\/public-work\\\/\",\"url\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/project-category\\\/public-work\\\/\",\"name\":\"Public work archivos - Huurre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/project-category\\\/public-work\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/project-category\\\/public-work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Public work\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/\",\"name\":\"Huurre\",\"description\":\"Paneles aislantes para edificios eficientes y sostenibles | Fabricamos paneles para fachadas, paredes interiores,\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.huurreiberica.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Public work archivos - Huurre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/","og_locale":"en_US","og_type":"article","og_title":"Public work archivos - Huurre","og_url":"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/","og_site_name":"Huurre","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/","url":"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/","name":"Public work archivos - Huurre","isPartOf":{"@id":"https:\/\/www.huurreiberica.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.huurreiberica.com\/en\/project-category\/public-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.huurreiberica.com\/en\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/www.huurreiberica.com\/en\/project\/"},{"@type":"ListItem","position":3,"name":"Public work"}]},{"@type":"WebSite","@id":"https:\/\/www.huurreiberica.com\/en\/#website","url":"https:\/\/www.huurreiberica.com\/en\/","name":"Huurre","description":"Paneles aislantes para edificios eficientes y sostenibles | Fabricamos paneles para fachadas, paredes interiores,","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.huurreiberica.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.huurreiberica.com\/en\/wp-json\/wp\/v2\/categoria-proyecto\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.huurreiberica.com\/en\/wp-json\/wp\/v2\/categoria-proyecto"}],"about":[{"href":"https:\/\/www.huurreiberica.com\/en\/wp-json\/wp\/v2\/taxonomies\/categoria-proyecto"}],"wp:post_type":[{"href":"https:\/\/www.huurreiberica.com\/en\/wp-json\/wp\/v2\/proyecto?categoria-proyecto=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}